{"id":665,"date":"2016-11-22T13:05:44","date_gmt":"2016-11-22T07:05:44","guid":{"rendered":"http:\/\/yucapedia.com\/?p=665"},"modified":"2016-12-12T10:00:22","modified_gmt":"2016-12-12T04:00:22","slug":"chemax-madero-del-mono","status":"publish","type":"post","link":"https:\/\/yucapedia.com\/index.php\/2016\/11\/22\/chemax-madero-del-mono\/","title":{"rendered":"Chemax (madero del mono)"},"content":{"rendered":"<p>El madero del mono, por derivarse de las voces Che, madero y max contracci\u00f3n de maax, mono, aunque podr\u00eda interpretarse tambi\u00e9n como madero majado, ya que la voz max equivale a majar, machucar. Tambi\u00e9n se acepta \u00ab\u00c1rbol de monos\u00bb.<\/p>\n<p><strong>Historia<\/strong><\/p>\n<p>Los datos fidedignos de la fundaci\u00f3n de Chemax se remontan al a\u00f1o de 1549 en el que se establece una Encomienda a favor de don Juan L\u00f3pez de Mena.<\/p>\n<p>El sitio en que hoy se encuentra la localidad de Chemax fue un antiguo poblado maya, perteneciente a la Provincia de los Cupules.<\/p>\n<p>La ma\u00f1ana del 4 de diciembre de 1847, el poblado de Chemax es atacado desde varios puntos, por ind\u00edgenas sublevados durante la llamada \u00abGuerra de Castas\u00bb. Poco falt\u00f3 para que esta poblaci\u00f3n cayera en manos de los rebeldes ya que sus defensores, encabezados por el capit\u00e1n Francisco Dom\u00ednguez, se hallaban pr\u00e1cticamente diezmados y faltos de parque. Acudi\u00f3 en su auxilio el capit\u00e1n Ferm\u00edn Irabi\u00e9n con tropas procedentes de Valladolid (pese a que la victoria acompa\u00f1\u00f3 a las fuerzas gubernamentales, dos semanas despu\u00e9s, se orden\u00f3 un repliegue hacia Valladolid de todos los efectivos castrenses, por lo que Chemax fue abandonado por sus moradores).<\/p>\n<p>En 1918, el pueblo de Chemax se erige en cabecera del municipio del mismo nombre por acuerdo de la \u00abLey Org\u00e1nica de los Municipios del Estado de Yucat\u00e1n\u00bb. Fue expedida el 7 de enero por el entonces gobernador comandante militar general Salvador Alvarado Rubio.<\/p>\n<p>En 1920, la localidad de Sisbicch\u00e9n dej\u00f3 de pertenecer a la jurisdicci\u00f3n municipal de Chemax.<\/p>\n<p>En 1966, se autoriz\u00f3 la creaci\u00f3n de un nuevo centro de poblaci\u00f3n: la unidad agr\u00edcola \u00abSan Rom\u00e1n\u00bb.<\/p>\n<p><strong>Monumentos hist\u00f3ricos<\/strong><\/p>\n<p>Las iglesias de San antonio de Padua, La Pur\u00edsima Concepci\u00f3n y San Pedro (siglos XVI y XVII), el Palacio Municipal (siglo XIX). Tambien se cuenta con monumentos arqueologicos como: Xalau, Tamba, Bolmay, Petul, Sotpol, Xuyap, Poxil, Xcoom, Palaban, Xmaos y Xcan.<\/p>\n<p><strong>Fiestas populares<\/strong><\/p>\n<p>Del 10 al 13 de junio se celebran las fiestas en honor a San Antonio de Padua, patrono del pueblo.<\/p>\n<p><strong>Poblaci\u00f3n<\/strong><\/p>\n<p>El municipio tiene 33,490 habitantes, de acuerdo con el Censo de Poblaci\u00f3n y Vivienda 2010.<\/p>\n<p>La cabecera del municipio es el pueblo de Chemax. Adem\u00e1s de la cabecera, dentro de la jurisdicci\u00f3n municipal quedan comprendidas cinco localidades: Catzim, Mucel, X-Can, Xalau y Sisbich\u00e9n. Adem\u00e1s, X-mab, Lolb\u00e9, Santa Cruz, San Pedro Chemax, San Juan Chen, Santa Elena, X-tejas, Uspibil, Kuxeb, Xochmil, X-maben, Xuneb, Punta Laguna y Cocoyol.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El madero del mono, por derivarse de las voces Che, madero y max contracci\u00f3n de<\/p>\n","protected":false},"author":1,"featured_media":667,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":""},"categories":[10],"tags":[],"jetpack_featured_media_url":"https:\/\/yucapedia.com\/wp-content\/uploads\/2016\/11\/chemax.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7Z0qv-aJ","_links":{"self":[{"href":"https:\/\/yucapedia.com\/index.php\/wp-json\/wp\/v2\/posts\/665"}],"collection":[{"href":"https:\/\/yucapedia.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/yucapedia.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/yucapedia.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/yucapedia.com\/index.php\/wp-json\/wp\/v2\/comments?post=665"}],"version-history":[{"count":1,"href":"https:\/\/yucapedia.com\/index.php\/wp-json\/wp\/v2\/posts\/665\/revisions"}],"predecessor-version":[{"id":666,"href":"https:\/\/yucapedia.com\/index.php\/wp-json\/wp\/v2\/posts\/665\/revisions\/666"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/yucapedia.com\/index.php\/wp-json\/wp\/v2\/media\/667"}],"wp:attachment":[{"href":"https:\/\/yucapedia.com\/index.php\/wp-json\/wp\/v2\/media?parent=665"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/yucapedia.com\/index.php\/wp-json\/wp\/v2\/categories?post=665"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/yucapedia.com\/index.php\/wp-json\/wp\/v2\/tags?post=665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}